{"id":13236,"date":"2026-06-25T09:11:05","date_gmt":"2026-06-25T07:11:05","guid":{"rendered":"https:\/\/www.sunnysideofthedoc.com\/?post_type=news&#038;p=13236"},"modified":"2026-07-01T09:35:21","modified_gmt":"2026-07-01T07:35:21","slug":"deux-journees-didees-de-rencontres-et-de-creation-documentaire-2","status":"publish","type":"news","link":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/","title":{"rendered":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9"},"content":{"rendered":"<div id=\"pl-13236\"  class=\"panel-layout\" ><div id=\"pg-13236-0\"  class=\"panel-grid panel-has-style\" ><div class=\"pt-50 pb-90 bg-pattern-left-top panel-row-style panel-row-style-for-13236-0\" ><div id=\"pgc-13236-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-13236-0-0-0\" class=\"so-panel widget widget_siteorigin-panels-builder panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"container panel-widget-style panel-widget-style-for-13236-0-0-0\" ><div id=\"pl-w6a44c339d4108\"  class=\"panel-layout\" ><div id=\"pg-w6a44c339d4108-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w6a44c339d4108-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6a44c339d4108-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h3>Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9<\/h3>\n<hr \/>\n<p>Pour cette derni\u00e8re journ\u00e9e de Sunny Side of the Doc 2026, les professionnels du documentaire venus du monde entier se sont retrouv\u00e9s une derni\u00e8re fois \u00e0 La Rochelle pour \u00e9changer, se rencontrer et imaginer l'avenir du secteur.<\/p>\n<\/div>\n<\/div><\/div><div id=\"panel-w6a44c339d4108-0-0-1\" class=\"so-panel widget widget_sow-image panel-last-child\" data-index=\"1\" ><div class=\"panel-widget-style panel-widget-style-for-w6a44c339d4108-0-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-image so-widget-sow-image-default-113ccd71f3e6\"\n\t\t\t\n\t\t>\n<div class=\"sow-image-container\">\n\t\t<img \n\tsrc=\"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-scaled.jpg\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-scaled.jpg 2560w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-300x200.jpg 300w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-1024x683.jpg 1024w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-768x512.jpg 768w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-2048x1365.jpg 2048w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-272x182.jpg 272w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-429x286.jpg 429w, https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/SSD26-5T5A2273\u00a9hugolafitte-810x540.jpg 810w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" title=\"SSD26 &#8211; 5T5A2273\u00a9hugolafitte\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n\t<\/div>\n\n<h3 class=\"widget-title\">SSD26 &#8211; 5T5A2273\u00a9hugolafitte<\/h3><\/div><\/div><\/div><\/div><\/div><div id=\"pg-w6a44c339d4108-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w6a44c339d4108-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-w6a44c339d4108-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-w6a44c339d4108-1-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Des discussions sur l\u2019hyperdistribution et la coproduction internationale aux r\u00e9flexions autour des archives, des nouvelles alliances et de l\u2019\u00e9volution du paysage documentaire, le Jour 3 a poursuivi l\u2019exploration des enjeux et des opportunit\u00e9s qui fa\u00e7onnent le futur du r\u00e9cit documentaire.<\/p>\n<p>Tout au long de la journ\u00e9e, les sessions Meet &amp; Match, les rencontres du CoPro Hub et les \u00e9changes informels ont favoris\u00e9 de nouvelles collaborations, confirmant le r\u00f4le de Sunny Side of the Doc comme un espace privil\u00e9gi\u00e9 o\u00f9 projets, partenariats et id\u00e9es peuvent se d\u00e9velopper.<\/p>\n<p>\u00c0 mesure que l\u2019\u00e9v\u00e9nement touchait \u00e0 sa fin, l\u2019attention s\u2019est port\u00e9e sur ce qui rend cette communaut\u00e9 si unique : les personnes qui la composent. Les derniers instants de cette \u00e9dition ont \u00e9t\u00e9 particuli\u00e8rement \u00e9mouvants, r\u00e9unissant les participants autour d\u2019un sentiment partag\u00e9 de gratitude, d\u2019inspiration et d\u2019appartenance. Sourires, accolades, larmes et au revoir sinc\u00e8res ont marqu\u00e9 cette cl\u00f4ture, rappelant qu\u2019au-del\u00e0 des projets et des opportunit\u00e9s professionnelles, Sunny Side of the Doc est avant tout une communaut\u00e9 r\u00e9unie par une m\u00eame passion pour le documentaire.<\/p>\n<p>D\u00e9couvrez la vid\u00e9o r\u00e9capitulative du Jour 3 et revivez les derniers moments de Sunny Side of the Doc 2026.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-w6a44c339d4108-2\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-w6a44c339d4108-2-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 Pour cette derni\u00e8re journ\u00e9e de Sunny Side of the Doc 2026, les professionnels du documentaire venus du monde entier se sont retrouv\u00e9s une derni\u00e8re fois \u00e0 La Rochelle pour \u00e9changer, se rencontrer et imaginer l&rsquo;avenir du secteur. SSD26 &#8211; 5T5A2273\u00a9hugolafitte Des discussions [&hellip;]<\/p>\n","protected":false},"featured_media":13242,"template":"","news_category":[],"class_list":["post-13236","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc\" \/>\n<meta property=\"og:description\" content=\"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 Pour cette derni\u00e8re journ\u00e9e de Sunny Side of the Doc 2026, les professionnels du documentaire venus du monde entier se sont retrouv\u00e9s une derni\u00e8re fois \u00e0 La Rochelle pour \u00e9changer, se rencontrer et imaginer l&#039;avenir du secteur. SSD26 &#8211; 5T5A2273\u00a9hugolafitte Des discussions [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunny Side of the Doc\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/sunnysideofthedoc\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T07:35:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/20260623-SUNNY-JF_AUGE-070-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/\",\"url\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/\",\"name\":\"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260623-SUNNY-JF_AUGE-070-scaled.jpg\",\"datePublished\":\"2026-06-25T07:11:05+00:00\",\"dateModified\":\"2026-07-01T07:35:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260623-SUNNY-JF_AUGE-070-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/20260623-SUNNY-JF_AUGE-070-scaled.jpg\",\"width\":2560,\"height\":1703},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/actualite\\\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#website\",\"url\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/\",\"name\":\"Sunny Side of the Doc\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#organization\",\"name\":\"Sunny Side of the Doc\",\"url\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-logo-vertical-blanc.png\",\"contentUrl\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-logo-vertical-blanc.png\",\"width\":1080,\"height\":1080,\"caption\":\"Sunny Side of the Doc\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sunnysideofthedoc.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sunnysideofthedoc\\\/\",\"https:\\\/\\\/x.com\\\/SunnySideDoc\",\"https:\\\/\\\/www.instagram.com\\\/sunnysidedoc\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sunnysideofthedoc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc","og_description":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 Pour cette derni\u00e8re journ\u00e9e de Sunny Side of the Doc 2026, les professionnels du documentaire venus du monde entier se sont retrouv\u00e9s une derni\u00e8re fois \u00e0 La Rochelle pour \u00e9changer, se rencontrer et imaginer l'avenir du secteur. SSD26 &#8211; 5T5A2273\u00a9hugolafitte Des discussions [&hellip;]","og_url":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/","og_site_name":"Sunny Side of the Doc","article_publisher":"https:\/\/www.facebook.com\/sunnysideofthedoc\/","article_modified_time":"2026-07-01T07:35:21+00:00","og_image":[{"width":2560,"height":1703,"url":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/20260623-SUNNY-JF_AUGE-070-scaled.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/","url":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/","name":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9 - Sunny Side of the Doc","isPartOf":{"@id":"https:\/\/www.sunnysideofthedoc.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/#primaryimage"},"image":{"@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/20260623-SUNNY-JF_AUGE-070-scaled.jpg","datePublished":"2026-06-25T07:11:05+00:00","dateModified":"2026-07-01T07:35:21+00:00","breadcrumb":{"@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/#primaryimage","url":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/20260623-SUNNY-JF_AUGE-070-scaled.jpg","contentUrl":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/06\/20260623-SUNNY-JF_AUGE-070-scaled.jpg","width":2560,"height":1703},{"@type":"BreadcrumbList","@id":"https:\/\/www.sunnysideofthedoc.com\/fr\/actualite\/deux-journees-didees-de-rencontres-et-de-creation-documentaire-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sunnysideofthedoc.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Jour 3 : une c\u00e9l\u00e9bration des id\u00e9es, des rencontres et de la communaut\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.sunnysideofthedoc.com\/#website","url":"https:\/\/www.sunnysideofthedoc.com\/","name":"Sunny Side of the Doc","description":"","publisher":{"@id":"https:\/\/www.sunnysideofthedoc.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sunnysideofthedoc.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.sunnysideofthedoc.com\/#organization","name":"Sunny Side of the Doc","url":"https:\/\/www.sunnysideofthedoc.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.sunnysideofthedoc.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/03\/cropped-logo-vertical-blanc.png","contentUrl":"https:\/\/www.sunnysideofthedoc.com\/wp-content\/uploads\/2026\/03\/cropped-logo-vertical-blanc.png","width":1080,"height":1080,"caption":"Sunny Side of the Doc"},"image":{"@id":"https:\/\/www.sunnysideofthedoc.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/sunnysideofthedoc\/","https:\/\/x.com\/SunnySideDoc","https:\/\/www.instagram.com\/sunnysidedoc\/","https:\/\/www.linkedin.com\/company\/sunnysideofthedoc\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/news\/13236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/media\/13242"}],"wp:attachment":[{"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/media?parent=13236"}],"wp:term":[{"taxonomy":"news_category","embeddable":true,"href":"https:\/\/www.sunnysideofthedoc.com\/fr\/wp-json\/wp\/v2\/news_category?post=13236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}